{"id":6269,"date":"2024-03-04T23:18:59","date_gmt":"2024-03-04T22:18:59","guid":{"rendered":"https:\/\/bicg.com\/uber-bicg\/allianzen\/"},"modified":"2025-03-06T23:34:01","modified_gmt":"2025-03-06T22:34:01","slug":"allianzen-old","status":"publish","type":"page","link":"https:\/\/bicg.com\/de\/uber-bicg\/allianzen-old\/","title":{"rendered":"Allianzen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6269\" class=\"elementor elementor-6269\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b16429a e-flex e-con-boxed e-con e-parent\" data-id=\"b16429a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99d00db elementor-widget elementor-widget-spacer\" data-id=\"99d00db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-384987e e-flex e-con-boxed e-con e-parent\" data-id=\"384987e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ea4e418 e-flex e-con-boxed e-con e-child\" data-id=\"ea4e418\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6675ca elementor-widget elementor-widget-heading\" data-id=\"d6675ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALLIANZEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3c56cb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e3c56cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0265791 e-flex e-con-boxed e-con e-child\" data-id=\"0265791\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57190ae e-flex e-con-boxed e-con e-parent\" data-id=\"57190ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-717b1ce elementor-widget elementor-widget-tp-animated-service-boxes\" data-id=\"717b1ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-animated-service-boxes.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ani_ser_box6a044f47bae95\" class=\"pt_plus_asb_wrapper image-accordion accordion-style-2 accordion-vertical  animate-general\" data-accordion-hover=\"yes\"  data-animate-type=\"transition.fadeIn\" data-animate-delay=\"50\" data-animate-offset=\"85%\"><div class=\"asb_wrap_list tp-row\"><div class=\"service-item-loop       \" style=\"flex-grow: 1;\"   data-flexgrow=\"10\"   ><img decoding=\"async\" class=\"theplus-image-accordion__image-instance loaded\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Thumb-Alianza-Fraunhofer.jpg\" alt=\"\">\n<div class=\"asb-content\" >\n\t<div class=\"asb-desc\"> <p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2560 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-Fraunhofer-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-Fraunhofer-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-Fraunhofer.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Fraunhofer es la mayor organizaci\u00f3n europea de investigaci\u00f3n orientada a la aplicaci\u00f3n. En sus propias palabras: \u00abNuestros esfuerzos de investigaci\u00f3n est\u00e1n totalmente orientados a las necesidades de las personas: salud, seguridad, comunicaci\u00f3n, energ\u00eda y medio ambiente. Como resultado, nuestro trabajo tiene un impacto significativo en la vida de las personas. Somos creativos. Damos forma a la tecnolog\u00eda. Dise\u00f1amos productos. Mejoramos los m\u00e9todos y las t\u00e9cnicas. Abrimos nuevas perspectivas. En resumen, forjamos el futuro\u00bb.<\/p> <\/div><\/div>\n\t\n<\/div><div class=\"service-item-loop       \" style=\"flex-grow: 1;\"   data-flexgrow=\"10\"   ><img decoding=\"async\" class=\"theplus-image-accordion__image-instance loaded\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Thumb-Alianza-EUWIN.jpg\" alt=\"\">\n<div class=\"asb-content\" >\n\t<div class=\"asb-desc\"> <p><img decoding=\"async\" class=\"aligncenter wp-image-2563 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-EUWIN-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-EUWIN-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-EUWIN.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>bicg pertenece a EUWIN, la Red Europea de Innovaci\u00f3n en el Lugar de Trabajo, una iniciativa lanzada en 2013 por la DG de Empresa e Industria de la Comisi\u00f3n Europea. Junto con muchos expertos de m\u00e1s de 30 pa\u00edses construimos una gran red compartiendo nuestros conocimientos y experiencia y colaborando entre nosotros.<\/p> <\/div><\/div>\n\t\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7916f0e elementor-widget elementor-widget-tp-animated-service-boxes\" data-id=\"7916f0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-animated-service-boxes.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ani_ser_box6a044f47bc001\" class=\"pt_plus_asb_wrapper image-accordion accordion-style-2 accordion-vertical  animate-general\" data-accordion-hover=\"yes\"  data-animate-type=\"transition.fadeIn\" data-animate-delay=\"50\" data-animate-offset=\"85%\"><div class=\"asb_wrap_list tp-row\"><div class=\"service-item-loop       \" style=\"flex-grow: 1;\"   data-flexgrow=\"10\"   ><img decoding=\"async\" class=\"theplus-image-accordion__image-instance loaded\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Thumb-Alianza-UPM.jpg\" alt=\"\">\n<div class=\"asb-content\" >\n\t<div class=\"asb-desc\"> <p data-wp-editing=\"1\"><img decoding=\"async\" class=\"aligncenter wp-image-2564 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-UPM-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-UPM-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-UPM.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>En 2015 creamos una c\u00e1tedra sobre \u2018Trabajo Digital\u2019 junto con la Universidad Polit\u00e9cnica de Madrid (UPM). La actividad de la C\u00e1tedra UPM-BICG \u2018Trabajo Digital\u2019 se centra en los retos del trabajo del conocimiento en la era digital y la adopci\u00f3n de tecnolog\u00edas en el contexto empresarial que puedan mejorar, por ejemplo, la productividad en las organizaciones.<\/p> <\/div><\/div>\n\t\n<\/div><div class=\"service-item-loop       \" style=\"flex-grow: 1;\"   data-flexgrow=\"10\"   ><img decoding=\"async\" class=\"theplus-image-accordion__image-instance loaded\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Thumb-Alianza-IDET.jpg\" alt=\"\">\n<div class=\"asb-content\" >\n\t<div class=\"asb-desc\"> <p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8422 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Alianza-IDET-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Alianza-IDET-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Alianza-IDET.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>IDET es la \u00fanica representante de los profesionales del entorno laboral en Francia. La Asociaci\u00f3n est\u00e1 administrada por un Comit\u00e9 de Directores que se apoya en varios a\u00f1os de experiencia para garantizar la buena marcha de la asociaci\u00f3n y su funcionamiento.<\/p> <\/div><\/div>\n\t\n<\/div><div class=\"service-item-loop       \" style=\"flex-grow: 1;\"   data-flexgrow=\"10\"   ><img decoding=\"async\" class=\"theplus-image-accordion__image-instance loaded\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Thumb-Alianza-MASFAMILIA.jpg\" alt=\"\">\n<div class=\"asb-content\" >\n\t<div class=\"asb-desc\"> <p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2561 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-MasFamilia-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-MasFamilia-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-MasFamilia.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>bicg colabora con la Fundaci\u00f3n Masfamilia sobre c\u00f3mo el trabajo flexible puede ayudar a las organizaciones a lograr un mejor equilibrio entre la vida profesional y personal. Hemos creado conjuntamente el Libro Blanco del Trabajo Flexible y ambas instituciones tienen un entendimiento com\u00fan sobre c\u00f3mo la implementaci\u00f3n de modelos de trabajo flexible crear\u00e1 organizaciones m\u00e1s eficientes, inclusivas, innovadoras y \u00e1giles. Hemos firmado la Carta de la Flexibilidad y tambi\u00e9n formamos parte de la red de organizaciones EFR.<\/p> <\/div><\/div>\n\t\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9b995e e-flex e-con-boxed e-con e-parent\" data-id=\"c9b995e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f9d54d9 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex elementor-invisible e-con e-child\" data-id=\"f9d54d9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a04bd0 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3a04bd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bicg.com\/de\/anpassung-und-veraenderungsmanagement-strategien-fuer-ein-zeitalter-der-ungewissheit\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/10\/Thumb-Insights-Ale-Senior-Talent.jpg\" class=\"attachment-medium_large size-medium_large wp-image-7896\" alt=\"talento senior\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/10\/Thumb-Insights-Ale-Senior-Talent.jpg 500w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/10\/Thumb-Insights-Ale-Senior-Talent-300x300.jpg 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/10\/Thumb-Insights-Ale-Senior-Talent-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7101ca2 e-con-full e-flex e-con e-child\" data-id=\"7101ca2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b05828c elementor-widget elementor-widget-heading\" data-id=\"b05828c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transformaci\u00f3n cultural: Claves para gestionar el cambio en tiempos de incertidumbre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68c81a5 elementor-widget elementor-widget-text-editor\" data-id=\"68c81a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">En un entorno de incertidumbre, la capacidad de adaptaci\u00f3n y gesti\u00f3n del cambio es clave para las organizaciones. En BICG, facilitamos la transformaci\u00f3n cultural<\/span> <span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">alineando a las personas con los objetivos del negocio, utilizando estrategias comprobadas para lograr un cambio sostenible y exitoso, adecuado para enfrentar los retos actuales.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4465618 elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"4465618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/bicg.com\/de\/anpassung-und-veraenderungsmanagement-strategien-fuer-ein-zeitalter-der-ungewissheit\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conoce m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26adfac e-con-full e-flex e-con e-child\" data-id=\"26adfac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad5bb04 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"ad5bb04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NjE4OSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfNecesitas nuestra ayuda?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e959a elementor-widget elementor-widget-spacer\" data-id=\"e4e959a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d64e708 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"d64e708\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/bicg.com\/de\/erfolgsgeschichten\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubre nuestras historias de \u00e9xito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b4192d e-flex e-con-boxed e-con e-parent\" data-id=\"7b4192d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f0289a elementor-widget elementor-widget-image\" data-id=\"9f0289a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"596\" height=\"204\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Logos-Justificacion.png\" class=\"attachment-medium_large size-medium_large wp-image-8658\" alt=\"\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Logos-Justificacion.png 596w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Logos-Justificacion-300x103.png 300w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5ec300 elementor-widget elementor-widget-text-editor\" data-id=\"e5ec300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #808080;\">Bicg<\/span><span style=\"color: #808080;\"> ha sido beneficiario del Programa de Mentoring y Apoyo a la internacionalizaci\u00f3n de la pyme. Entre otros gastos, la empresa ha cofinanciado con estos fondos material de difusi\u00f3n y promoci\u00f3n, en concreto la participaci\u00f3n como oyentes y\/o ponentes en los eventos Future Workplace 2024 (Handelsblatt) y Smart Workspace Design (Amsterdam), dise\u00f1o y montaje de stand en la Feria AMEDIRH (M\u00e9xico), organizaci\u00f3n Evento 25 a\u00f1os (M\u00e9xico), as\u00ed como traducciones de contenido web a otros idiomas y trabajos de posicionamiento SEO.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9c915b elementor-widget elementor-widget-spacer\" data-id=\"e9c915b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fa94f9 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"4fa94f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e2a97cb e-con-full e-flex e-con e-child\" data-id=\"e2a97cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8d206 elementor-tabs-view-vertical elementor-widget elementor-widget-tp-tabs-tours\" data-id=\"6b8d206\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-tabs-tours.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"theplus-tabs-wrapper  elementor-tabs  nav-full-width    tp-tab-playloop \" id=\"tabs6a047e47db5cc\" data-tabs-id=\"tabs6a047e47db5cc\"  data-connection=\"\"   data-tab-default=\"0\" data-tab-hover=\"yes\" data-tab-autoplay=\"yes\" data-tab-autoplay-duration=\"10\"  role=\"tablist\"><div class=\"theplus-tabs-nav-wrapper elementor-tabs-wrapper text-center align-top   \"><ul class=\"plus-tabs-nav      \"><li class=\"\"><div id=\"elementor-tab-title-1121\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"1\" tabindex=\"1121\" role=\"tab\" aria-controls=\"elementor-tab-content-1121\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>Fraunhofer<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-1122\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"2\" tabindex=\"1122\" role=\"tab\" aria-controls=\"elementor-tab-content-1122\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>EUWIN<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-1123\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"3\" tabindex=\"1123\" role=\"tab\" aria-controls=\"elementor-tab-content-1123\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>Universidad Polit\u00e9cnica de Madrid<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-1124\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"4\" tabindex=\"1124\" role=\"tab\" aria-controls=\"elementor-tab-content-1124\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>IDET<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-1125\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"5\" tabindex=\"1125\" role=\"tab\" aria-controls=\"elementor-tab-content-1125\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>Fundaci\u00f3n Masfamilia<\/span><\/div><\/li><\/ul><\/div><div class=\"theplus-tabs-content-wrapper  elementor-tabs-content-wrapper\"><div class=\"elementor-tab-title elementor-tab-mobile-title text-center \" tabindex=\"1121\" data-tab=\"1\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>Fraunhofer<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"1\" role=\"tabpanel\"><div class=\"plus-content-editor\"><p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2560 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-Fraunhofer-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-Fraunhofer-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-Fraunhofer.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Fraunhofer es la mayor organizaci\u00f3n europea de investigaci\u00f3n orientada a la aplicaci\u00f3n. En sus propias palabras: \u00abNuestros esfuerzos de investigaci\u00f3n est\u00e1n totalmente orientados a las necesidades de las personas: salud, seguridad, comunicaci\u00f3n, energ\u00eda y medio ambiente. Como resultado, nuestro trabajo tiene un impacto significativo en la vida de las personas. Somos creativos. Damos forma a la tecnolog\u00eda. Dise\u00f1amos productos. Mejoramos los m\u00e9todos y las t\u00e9cnicas. Abrimos nuevas perspectivas. En resumen, forjamos el futuro\u00bb.<\/p><\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-center \" tabindex=\"1122\" data-tab=\"2\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>EUWIN<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"2\" role=\"tabpanel\"><div class=\"plus-content-editor\"><p><img decoding=\"async\" class=\"aligncenter wp-image-2563 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-EUWIN-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-EUWIN-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-EUWIN.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: left;\">bicg pertenece a EUWIN, la Red Europea de Innovaci\u00f3n en el Lugar de Trabajo, una iniciativa lanzada en 2013 por la DG de Empresa e Industria de la Comisi\u00f3n Europea. Junto con muchos expertos de m\u00e1s de 30 pa\u00edses construimos una gran red compartiendo nuestros conocimientos y experiencia y colaborando entre nosotros.<\/p><\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-center \" tabindex=\"1123\" data-tab=\"3\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>Universidad Polit\u00e9cnica de Madrid<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"3\" role=\"tabpanel\"><div class=\"plus-content-editor\"><p data-wp-editing=\"1\"><img decoding=\"async\" class=\"aligncenter wp-image-2564 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-UPM-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-UPM-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-UPM.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>En 2015 creamos una c\u00e1tedra sobre \u2018Trabajo Digital\u2019 junto con la Universidad Polit\u00e9cnica de Madrid (UPM). La actividad de la C\u00e1tedra UPM-BICG \u2018Trabajo Digital\u2019 se centra en los retos del trabajo del conocimiento en la era digital y la adopci\u00f3n de tecnolog\u00edas en el contexto empresarial que puedan mejorar, por ejemplo, la productividad en las organizaciones.<\/p><\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-center \" tabindex=\"1124\" data-tab=\"4\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>IDET<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"4\" role=\"tabpanel\"><div class=\"plus-content-editor\"><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8422 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Alianza-IDET-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Alianza-IDET-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/11\/Alianza-IDET.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>IDET es la \u00fanica representante de los profesionales del entorno laboral en Francia. La Asociaci\u00f3n est\u00e1 administrada por un Comit\u00e9 de Directores que se apoya en varios a\u00f1os de experiencia para garantizar la buena marcha de la asociaci\u00f3n y su funcionamiento.<\/p><\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-center \" tabindex=\"1125\" data-tab=\"5\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-plus\"><\/i><\/span><span>Fundaci\u00f3n Masfamilia<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"5\" role=\"tabpanel\"><div class=\"plus-content-editor\"><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2561 size-medium\" src=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-MasFamilia-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-MasFamilia-300x180.png 300w, https:\/\/bicg.com\/wp-content\/uploads\/2024\/02\/Alianza-MasFamilia.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>bicg colabora con la Fundaci\u00f3n Masfamilia sobre c\u00f3mo el trabajo flexible puede ayudar a las organizaciones a lograr un mejor equilibrio entre la vida profesional y personal. Hemos creado conjuntamente el Libro Blanco del Trabajo Flexible y ambas instituciones tienen un entendimiento com\u00fan sobre c\u00f3mo la implementaci\u00f3n de modelos de trabajo flexible crear\u00e1 organizaciones m\u00e1s eficientes, inclusivas, innovadoras y \u00e1giles. Hemos firmado la Carta de la Flexibilidad y tambi\u00e9n formamos parte de la red de organizaciones EFR.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ALLIANZEN Fraunhofer es la mayor organizaci\u00f3n europea de investigaci\u00f3n orientada a la aplicaci\u00f3n. En sus propias palabras: \u00abNuestros esfuerzos de investigaci\u00f3n est\u00e1n totalmente orientados a las necesidades de las personas: salud, seguridad, comunicaci\u00f3n, energ\u00eda y medio ambiente. Como resultado, nuestro trabajo tiene un impacto significativo en la vida de las personas. Somos creativos. Damos forma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":6117,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6269","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/pages\/6269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/comments?post=6269"}],"version-history":[{"count":2,"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/pages\/6269\/revisions"}],"predecessor-version":[{"id":8825,"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/pages\/6269\/revisions\/8825"}],"up":[{"embeddable":true,"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/pages\/6117"}],"wp:attachment":[{"href":"https:\/\/bicg.com\/de\/wp-json\/wp\/v2\/media?parent=6269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}